{"id":1803,"date":"2022-10-10T19:16:02","date_gmt":"2022-10-10T19:16:02","guid":{"rendered":"https:\/\/casabenissa.nl\/?p=1803"},"modified":"2024-05-08T09:00:28","modified_gmt":"2024-05-08T09:00:28","slug":"officiele-gemeenschapsgids-van-valencia-voor-eigenaars-van-vakantiewoningen","status":"publish","type":"post","link":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/","title":{"rendered":"Gu\u00eda oficial de la Comunidad Valenciana para propietarios de viviendas vacacionales"},"content":{"rendered":"<p><em>Esta es una traducci\u00f3n al holand\u00e9s de la Gu\u00eda Oficial de la Comunidad Valenciana para propietarios de viviendas vacacionales. <\/em><em>No se pueden derivar derechos de esta p\u00e1gina y\/o de la traducci\u00f3n.<br \/>\nEspa\u00f1ol: Consejo General de Colegios de Administradores de Fincas.<br \/>\nGu\u00eda oficial de la Comunidad Valenciana para propietarios de alquiler vacacional. <\/em><\/p>\n<p><em>Descargue la traducci\u00f3n al ingl\u00e9s aqu\u00ed <a href=\"https:\/\/casabenissa.nl\/wp-content\/uploads\/OFFICIELE-GEMEENSCHAPSGIDS-VAN-VALENCIA-VOOR-EIGENAARS-VAN-VAKANTIEVERHUUR.pdf\" target=\"_blank\" rel=\"noopener\">Holand\u00e9s<\/a> o <a href=\"https:\/\/casabenissa.nl\/wp-content\/uploads\/MP-HOLIDAY-RENTAL-.pdf\" target=\"_blank\" rel=\"noopener\">Ingl\u00e9s<\/a><\/em><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-1814 alignright\" src=\"https:\/\/casabenissa.nl\/wp-content\/uploads\/logo_turisme_cv-300x133.png\" alt=\"\" width=\"300\" height=\"133\" srcset=\"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/logo_turisme_cv-300x133.png 300w, https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/logo_turisme_cv.png 419w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/em><\/p>\n<p class=\"p8\"><b>Tabla de contenido:<\/b><\/p>\n<p class=\"p8\"><b>INTRODUCCI\u00d3N<\/b><\/p>\n<p class=\"p3\">1.<span class=\"Apple-converted-space\">\u00a0 \u00a0 <\/span>Definici\u00f3n de vivienda vacacional en la Comunidad Valenciana<br \/>\n1.1. \u00bfCu\u00e1l es la definici\u00f3n de vivienda vacacional en la Comunidad Valenciana?<br \/>\n1.2. \u00bfQu\u00e9 NO se considera alquiler vacacional y cu\u00e1les son las excepciones?<br \/>\n1.3. Diferentes tipos de casas de vacaciones<br \/>\n1.4. Categor\u00edas y requisitos para alquileres vacacionales<\/p>\n<p class=\"p3\">2 Obligaciones y responsabilidades de los propietarios de viviendas vacacionales<br \/>\n2.1. REGISTRO de viviendas vacacionales<br \/>\n2.2. C\u00f3mo registrar o modificar licencias existentes<span class=\"Apple-converted-space\"><br \/>\n<\/span>2.3. Comercializaci\u00f3n de viviendas vacacionales<br \/>\n2.4. Recepci\u00f3n de hu\u00e9spedes en su alojamiento<br \/>\n2.5. Eficiencia energ\u00e9tica<br \/>\n2.6. C\u00f3mo obtener un libro de quejas y notificaciones<br \/>\n2.7. Registro de invitados<br \/>\n2.8. Responsabilidades de los propietarios y de los hu\u00e9spedes en relaci\u00f3n con la comunidad de propietarios<br \/>\n2.9. Cumplimiento del RGPD<br \/>\n2.10. Obligaciones fiscales y laborales relativas a los empleados, tales como personal de limpieza y otros prestadores de servicios subcontratados.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p3\">3 Derechos del propietario de una vivienda vacacional<br \/>\n3.1. Dep\u00f3sito<br \/>\n3.2. Cancelaciones<br \/>\n3.3. Propiedades vacantes<br \/>\n3.4. Derechos de los hu\u00e9spedes a disfrutar de las instalaciones<span class=\"Apple-converted-space\"><br \/>\n<\/span>3.5. Resoluciones<\/p>\n<p class=\"p3\">4. Sanciones y multas<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"p1\">1.<span class=\"Apple-converted-space\">\u00a0 \u00a0 <\/span>Definici\u00f3n de vivienda vacacional en la Comunidad Valenciana<\/h2>\n<p class=\"p3\"><b>INTRODUCCI\u00d3N:<\/b><\/p>\n<p class=\"p3\">El Decreto 30\/1993 del Consejo aprob\u00f3 la primera regulaci\u00f3n de apartamentos tur\u00edsticos, villas, chalets, bungalows y similares, que otorg\u00f3 derechos naturales en la Comunidad Valenciana a un tipo de alojamiento tur\u00edstico diferente al ofertado en hoteles y campamentos tur\u00edsticos: las viviendas tur\u00edsticas.<\/p>\n<p class=\"p3\">M\u00e1s de quince a\u00f1os despu\u00e9s, el Decreto 92\/2009, de 3 de julio, del Consejo, aprob\u00f3 un nuevo marco regulador para los alojamientos tur\u00edsticos, denominados apartamentos, villas, bungalows y similares, y para las empresas gestoras, personas jur\u00eddicas o personas f\u00edsicas responsables de su uso y disfrute, en la Comunidad Valenciana. Fue modificado por tres decretos posteriores: 206\/2010, de 3 de diciembre; 22\/2012, de 27 de enero; y 75\/2015, de 15 de mayo.<\/p>\n<p class=\"p10\">Este manual est\u00e1 dirigido principalmente a los propietarios de viviendas tur\u00edsticas que alquilan la propiedad directamente, con car\u00e1cter comercial, a usuarios tur\u00edsticos, sin recurrir a empresas de gesti\u00f3n de alquileres vacacionales.<\/p>\n<h3 class=\"p11\"><b>1.1. \u00bfCu\u00e1l es la definici\u00f3n de vivienda vacacional en la Comunidad Valenciana?<\/b><\/h3>\n<p class=\"p3\">En la Comunidad Valenciana se considera \u201cvivienda tur\u00edstica\u201d aquel inmueble que cumple los siguientes requisitos:<\/p>\n<ol class=\"ol1\">\n<li class=\"li12\"><span class=\"s2\">Significa \u201capartamentos, villas, chalets, bungalows y similares\u201d<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Para uso de:<\/span><\/li>\n<\/ol>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">Por precio<\/span>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">regularmente<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">disponible de inmediato<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">con fines tur\u00edsticos, vacacionales o de ocio<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p class=\"p3\">La regularidad puede definirse por una de las siguientes condiciones:<\/p>\n<ol class=\"ol2\">\n<li class=\"li12\"><span class=\"s2\">Para uso tur\u00edstico a trav\u00e9s de una empresa de gesti\u00f3n de alquiler vacacional<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Disponible para fines tur\u00edsticos, directamente de los propietarios, independientemente de la duraci\u00f3n del alquiler, siempre que se presten servicios de restauraci\u00f3n, como limpieza, suministro de ropa de cama y toallas, servicios de lavander\u00eda y mantenimiento o similares.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Cuando la propiedad se presenta a los turistas a trav\u00e9s de canales como plataformas de alquiler vacacional, Internet u otras formas de tecnolog\u00eda.<\/span><\/li>\n<\/ol>\n<h3 class=\"p11\"><b>1.2. \u00bfQu\u00e9 NO se considera una casa de vacaciones y cu\u00e1les son las excepciones?<br \/>\n<\/b><\/h3>\n<ol class=\"ol2\">\n<li class=\"li12\"><span class=\"s2\">Viviendas arrendadas por temporada seg\u00fan lo establecido en la Ley 29\/1994 de Arrendamientos Urbanos y en la Ley 8\/2004, de 20 de octubre, de Vivienda de la Comunidad Valenciana, para usos distintos del tur\u00edstico, vacacional u ocio.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">\u201cApartahoteles\u201d tal y como los define el DECRETO 75\/2015, de 15 de mayo, del Consell, regulador de los establecimientos hoteleros de la Comunidad Valenciana.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Caba\u00f1as, bungalows o \u201cmobil homes\u201d ubicados en los campings acogidos al DECRETO 6\/2015, de 23 de enero, del Consell, \u00f3rgano supervisor de los campings y zonas de tr\u00e1nsito de autocaravanas de la Comunitat Valenciana.<\/span><\/li>\n<\/ol>\n<h3 class=\"p11\"><b>1.3. Diferentes tipos de casas de vacaciones<\/b><\/h3>\n<p class=\"p3\">El reglamento no define apartamento, villa, castillo y bungalow, pero en el diccionario espa\u00f1ol aparecen definidos de la siguiente manera:<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\"><b>Departamento: <\/b>Apartamento peque\u00f1o para vivir. Vivienda unifamiliar en un edificio de varias plantas, que suele constar de una o dos habitaciones, cocina y ba\u00f1o.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Villa: <\/b>Una casa de vacaciones situada en un entorno rural aislado. Una casa con jard\u00edn en el campo, generalmente aislada de las dem\u00e1s y utilizada para el descanso o la recreaci\u00f3n durante las estaciones.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Chalet: <\/b>Edificio de una o m\u00e1s plantas, con jard\u00edn, dise\u00f1ado espec\u00edficamente para viviendas unifamiliares. O bien, una vivienda unifamiliar de una o m\u00e1s plantas, generalmente rodeada de jardines.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Palacio: <\/b>chalet cuyas paredes colindan con otra casa de iguales o similares caracter\u00edsticas.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Bungalow: <\/b>Edificio de planta baja<\/span><\/li>\n<\/ul>\n<p class=\"p3\">Y otros <b>casas similares,<\/b> es decir, todos los dem\u00e1s inmuebles cerrados y cubiertos que tienen la distribuci\u00f3n, instalaciones, equipamiento y dem\u00e1s condiciones para ser ocupados por personas, y son en consecuencia aptos para su uso como vivienda.<\/p>\n<h3 class=\"p11\"><b>1.4. Categor\u00edas y requisitos para alquileres vacacionales<\/b><\/h3>\n<p class=\"p3\">Los alojamientos tur\u00edsticos de la Comunitat Valenciana se dividen en tres categor\u00edas: superior, primera y est\u00e1ndar.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ol class=\"ol1\">\n<li class=\"li12\"><b><\/b><span class=\"s2\"><b>Acceso, comunicaci\u00f3n y aparcamiento<\/b><\/span><\/li>\n<\/ol>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">Ascensor<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Aparcamiento<br \/>\n<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<ol class=\"ol1\">\n<li class=\"li12\"><span class=\"s2\"><b>Instalaciones y servicios<\/b><br \/>\n<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Superficie construida m2 del edificio<\/b><br \/>\n<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><span class=\"s2\"><b>Instalaciones de vivienda <\/b><br \/>\nEn general, todos los alojamientos deben estar equipados con muebles, cuberter\u00eda, menaje de cocina, ropa de cama y dem\u00e1s utensilios y accesorios necesarios para satisfacer las necesidades de los hu\u00e9spedes seg\u00fan sus capacidades. Todas las habitaciones deben tener armario, tanto interior como exterior.<\/span><\/span>Los alojamientos tur\u00edsticos de categor\u00eda superior y primera deben estar equipados con televisi\u00f3n a color. La cocina debe contar con al menos dos placas el\u00e9ctricas si el alojamiento tiene capacidad para un m\u00e1ximo de cuatro personas, y con tres o m\u00e1s si supera esta capacidad. Tambi\u00e9n debe estar equipada con refrigerador, cocina el\u00e9ctrica, horno\/microondas y extractor de humos. Los alojamientos de categor\u00eda superior y primera deben estar equipados con lavadora autom\u00e1tica, y los apartamentos de categor\u00eda superior tambi\u00e9n disponen de lavavajillas.<\/li>\n<\/ol>\n<h2 class=\"p11\"><b>2. Obligaciones y responsabilidades de los propietarios de viviendas vacacionales<\/b><\/h2>\n<h3 class=\"p11\"><b>2.1. Registro de viviendas de alquiler vacacional<\/b><\/h3>\n<p class=\"p3\">Completar la declaraci\u00f3n de conformidad que acompa\u00f1a a la vivienda vacacional.<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><a href=\"http:\/\/www.gva.es\/downloads\/publicados\/IN\/25082_BI.pdf\" target=\"_blank\" rel=\"noopener\"><span class=\"s3\">Descargar aqu\u00ed<\/span><\/a><span class=\"s2\"> El formulario para propietarios privados.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/li>\n<li class=\"li12\"><a href=\"http:\/\/www.gva.es\/downloads\/publicados\/IN\/25081_BI.pdf\" target=\"_blank\" rel=\"noopener\"><span class=\"s3\">Descargar aqu\u00ed<\/span><\/a><span class=\"s2\"> El formulario para administradores de propiedades.<\/span><\/li>\n<\/ul>\n<p class=\"p3\">Se deber\u00e1n adjuntar al formulario los siguientes documentos:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">Copia de la escritura de constituci\u00f3n inscrita en el Registro Mercantil y del n\u00famero de identificaci\u00f3n fiscal de la sociedad u otro documento que acredite su constituci\u00f3n, as\u00ed como la constancia de cualquier facultad, si \u00e9sta no conste claramente en los citados documentos.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Fotocopia del documento nacional de identidad de la persona o documento de identificaci\u00f3n equivalente.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Si el titular es extranjero, fotocopia de su documento o tarjeta de identidad extranjero, o fotocopia de su autorizaci\u00f3n de trabajo por cuenta propia en vigor.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Permiso de residencia para la vivienda vacacional.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Listado de casas de vacaciones.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p class=\"p3\">Por favor env\u00ede el formulario de la siguiente manera:<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">A trav\u00e9s del Registro de Servicios Tur\u00edsticos de la provincia donde se ubica el inmueble (o donde se ubican la mayor parte de los negocios de alquiler vacacional, en el caso de empresas gestoras de viviendas tur\u00edsticas), cualquier \u00f3rgano administrativo perteneciente a la administraci\u00f3n p\u00fablica estatal o auton\u00f3mica o alguno de los organismos que integran el gobierno local.<br \/>\nEn este \u00faltimo caso, dichas partes deber\u00e1n ser firmantes del convenio colectivo correspondiente.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Oficinas de correos, preferiblemente a las siguientes direcciones:<\/span>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\">Registro del Servicio Territorial de Turismo de Valencia, Plaza Alfonso el Magn\u00e1nimo 15, 46003 Valencia.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Registro del Servicio Territorial de Turismo de Castell\u00f3n, Avenida Hermanos Bou 47, 12003 Castell\u00f3n de la Plana.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">Registro del Servicio Territorial de Turismo de Alicante, Calle Churruca 29, 03003 Alicante.<br \/>\n<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<li class=\"li12\"><span class=\"s2\">Agencias diplom\u00e1ticas u oficinas consulares espa\u00f1olas en el extranjero.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/li>\n<li class=\"li12\"><span class=\"s2\">El registro electr\u00f3nico de la Comunidad Valenciana, al que se puede acceder a trav\u00e9s de este enlace.<\/span><\/li>\n<\/ul>\n<h3 class=\"p11\"><b>2.2. Registro o modificaci\u00f3n de licencias existentes<\/b><\/h3>\n<p class=\"p3\">La declaraci\u00f3n de inicio de la actividad deber\u00e1 realizarse con car\u00e1cter previo, debiendo iniciarse la misma en el plazo m\u00e1ximo de dos meses desde la presentaci\u00f3n de la misma.<\/p>\n<p class=\"p3\">Por otro lado, los cambios no podr\u00e1n ser implementados una vez realizados, ni la actividad podr\u00e1 ser cerrada dentro de los quince d\u00edas siguientes al evento.<\/p>\n<p class=\"p3\">El tratamiento puede tener lugar de diferentes maneras:<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s2\"><b>Personal: <\/b>Presentar la declaraci\u00f3n en el registro de la Direcci\u00f3n Territorial Provincial de Turismo, en los \u00f3rganos correspondientes de los \u00f3rganos de gobierno de la Administraci\u00f3n del Estado, as\u00ed como en las misiones diplom\u00e1ticas u oficinas consulares de Espa\u00f1a en el extranjero.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Por correo: <\/b>En cualquier oficina de correos, con el sobre abierto para poder estampar en el formulario y en la copia el sello y la fecha de solicitud.<\/span><\/li>\n<li class=\"li12\"><span class=\"s2\"><b>Internet:<\/b> Utilizando firma electr\u00f3nica a trav\u00e9s del siguiente enlace:<br \/>\n<a href=\"https:\/\/www.sede.fnmt.gob.es\/inicio\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/www.sede.fnmt.gob.es\/inicio<\/span><\/a><\/span><\/li>\n<\/ul>\n<p class=\"p3\"><span class=\"s4\"><br \/>\n<\/span>La presentaci\u00f3n de la declaraci\u00f3n habilita para el inicio de la actividad de alquiler.<\/p>\n<p class=\"p3\">No obstante, la Oficina Territorial de Turismo podr\u00e1 solicitar su correcci\u00f3n si detecta omisiones o inexactitudes. Si dichas omisiones se consideran significativas, se podr\u00e1n suspender las actividades de alquiler.<\/p>\n<p class=\"p3\">La inscripci\u00f3n es gratuita.<\/p>\n<h3 class=\"p11\"><b>2.3. Comercializaci\u00f3n de propiedades de alquiler vacacional<\/b><\/h3>\n<ol class=\"ol2\">\n<li class=\"li12\"><span class=\"s2\"><span class=\"s2\"><b>El anuncio<\/b>, \u00c9l <b>oferta<\/b> y <b>la gerencia<\/b> El alojamiento tur\u00edstico deber\u00e1 ser veraz y objetivo y proporcionar al hu\u00e9sped informaci\u00f3n suficiente sobre el inmueble en alquiler, las condiciones de uso y los servicios incluidos en el alquiler.<\/span><\/span>Todas las marcas en la propiedad de alquiler deben indicar claramente el n\u00famero de registro y la categor\u00eda de la propiedad.<\/li>\n<li class=\"li12\"><span class=\"s2\"><span class=\"s2\"><b>Las caracter\u00edsticas de una casa de vacaciones<\/b>:<\/span><\/span>En la entrada de la vivienda de alquiler, tanto en el interior como en el exterior, debe colocarse de forma visible una placa con el n\u00famero de registro y la categor\u00eda. Estas placas est\u00e1n reguladas por el Decreto 2\/2017, de 24 de enero, que establece sus caracter\u00edsticas espec\u00edficas: La placa de vinilo adhesivo debe ser roja (Pantone 485), de 200 x 76 mm, con un di\u00e1metro aproximado de 6 micras, y recortada con plotter con un radio de esquina de 10 mm. El n\u00famero de registro de cada vivienda debe figurar en la parte superior, con la silueta de un llavero con forma de casa, y debe llevar el logotipo institucional de la Comunitat Valenciana. Puede descargar aqu\u00ed plantillas PDF editables para crear la placa. <a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/index.jsp\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/index.jsp<\/span><\/a><\/li>\n<\/ol>\n<h3 class=\"p11\"><b>2.4. Recepci\u00f3n de hu\u00e9spedes en su alojamiento<\/b><\/h3>\n<p class=\"p14\">Los propietarios deber\u00e1n mantener las viviendas tur\u00edsticas en perfecto estado de habitabilidad, de acuerdo con su categor\u00eda y la descripci\u00f3n facilitada a la Oficina de Turismo.<\/p>\n<p class=\"p14\">Los hu\u00e9spedes est\u00e1n obligados a respetar las instalaciones tanto de la vivienda en alquiler como las zonas e instalaciones comunes del edificio o urbanizaci\u00f3n en el que se encuentren.<\/p>\n<p class=\"p14\">El incumplimiento de estas normas podr\u00e1 ser motivo de resoluci\u00f3n del contrato de alojamiento tur\u00edstico, previo preaviso entre las partes y sin perjuicio de lo dispuesto en otros acuerdos.<\/p>\n<h3 class=\"p11\"><b>2.5. Eficiencia energ\u00e9tica<\/b><\/h3>\n<p class=\"p14\"><span class=\"s5\"><br \/>\n<\/span>El Decreto 235\/2013, de 5 de abril, establece la necesidad de obtener un certificado de eficiencia energ\u00e9tica para la vivienda en alquiler.<\/p>\n<p class=\"p14\">Viviendas que se alquilan por menos de cuatro meses al a\u00f1o, o donde el consumo de energ\u00eda es inferior al 25% del consumo que resultar\u00eda en un a\u00f1o completo.<\/p>\n<p class=\"p14\">Este certificado debe ser realizado por un t\u00e9cnico cualificado y registrado en la Agencia Valenciana de la Energ\u00eda (AVEN): <a href=\"https:\/\/sgcee.aven.es\/sigenervs\/default.aspx\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/sgcee.aven.es\/sigenervs\/default.aspx<\/span><\/a><\/p>\n<p class=\"p14\">El Certificado tiene una validez de diez a\u00f1os y deber\u00e1 ponerse a disposici\u00f3n del hu\u00e9sped cuando \u00e9ste lo solicite.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<h3 class=\"p11\"><b>2.6. C\u00f3mo obtener un libro de quejas y la notificaci\u00f3n obligatoria:<\/b><\/h3>\n<p class=\"p14\">El propietario o la empresa gestora autorizada de las propiedades en alquiler debe proporcionar a los hu\u00e9spedes un folleto de reclamaciones. Este folleto est\u00e1 disponible en la Consejer\u00eda Territorial de Comercio y Consumo y debe abonarse por adelantado. Los detalles de pago est\u00e1n disponibles aqu\u00ed: <a href=\"https:\/\/hisenda.gva.es\/va\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/hisenda.gva.es\/va\/<\/span><\/a><\/p>\n<p class=\"p14\">Para obtener la firma obligatoria que indica la existencia del Libro de Quejas, por favor consulte el siguiente enlace:<\/p>\n<h3 class=\"p11\"><b>2.7. Registro de invitados<\/b><\/h3>\n<p class=\"p14\">El Decreto 1513\/1959, de 18 de agosto, exige a los establecimientos hoteleros mantener una lista de hu\u00e9spedes. Esta obligaci\u00f3n se extendi\u00f3 a otras modalidades de alojamiento, como los alquileres tur\u00edsticos, mediante el Decreto 393\/1974, de 7 de febrero.<\/p>\n<p class=\"p14\">La Orden INT\/1922\/2003, de 3 de julio, establece la obligaci\u00f3n de elaborar registros y datos de reservas de los viajeros.<\/p>\n<p class=\"p14\">La fecha de llegada y la duraci\u00f3n deber\u00e1n constar en el registro y deber\u00e1n ser firmados tanto por el hu\u00e9sped como por el propietario o empresa gestora autorizada.<\/p>\n<p class=\"p14\">La matriculaci\u00f3n debe presentarse ante la Polic\u00eda Nacional o la Guardia Civil (seg\u00fan la ciudad) dentro de las veinticuatro horas siguientes al inicio del periodo de alquiler. La matriculaci\u00f3n puede presentarse de las siguientes maneras:<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><span class=\"s6\">Personal<\/span><\/li>\n<li class=\"li12\"><span class=\"s6\">Faxes<\/span><\/li>\n<li class=\"li12\"><span class=\"s6\">En l\u00ednea a trav\u00e9s de los siguientes enlaces:<\/span>\n<ul class=\"ul1\">\n<li style=\"list-style-type: none;\">\n<ul class=\"ul1\">\n<li class=\"li12\"><a href=\"https:\/\/hospederias.guardiacivil.es\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s7\">https:\/\/hospederias.guardiacivil.es\/<\/span><\/a><\/li>\n<li class=\"li12\"><a href=\"https:\/\/webpol.policia.es\/e-hotel\/#\" target=\"_blank\" rel=\"noopener\"><span class=\"s7\">https:\/\/webpol.policia.es\/e-hotel\/#<\/span><\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p class=\"p14\">El propietario o la empresa gestora de alquileres autorizada deben conservar los registros de registro en archivos\/carpetas\/libros con un m\u00e1ximo de 100 a 500 entradas. Estos registros deben conservarse durante al menos tres a\u00f1os, a partir de la \u00faltima entrada en el archivo\/carpeta\/libro.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p14\">Deber\u00e1 ser accesible en todo momento para Las Fuerza y Cuerpos de Seguridad.<\/p>\n<h3 class=\"p11\"><b>2.8. Responsabilidades de los propietarios y de los hu\u00e9spedes en relaci\u00f3n con la comunidad de propietarios<\/b><\/h3>\n<ol class=\"ol2\">\n<li class=\"li12\"><span class=\"s6\"><span class=\"s6\"><b>Normas comunitarias que pueden restringir la posibilidad de alquiler a turistas.<\/b><br \/>\nEl cumplimiento de las disposiciones del Decreto 920\/2009 sobre alquileres vacacionales puede no ser siempre suficiente para alquilar legalmente una vivienda como alojamiento tur\u00edstico. Otras normativas p\u00fablicas o privadas pueden restringir o incluso impedir esta actividad en determinadas zonas.<br \/>\nPor ello, en las viviendas que forman parte de una comunidad de propietarios, ya sea en un bloque de viviendas o en una urbanizaci\u00f3n, es fundamental comprobar que los estatutos y normas de la comunidad no proh\u00edban o restrinjan esta actividad.<\/span><\/span>Si un propietario a\u00fan no dispone de los estatutos, puede solicitarlos al administrador de la Comunidad de Propietarios o al Registro de la Propiedad. Por regla general, solo una norma incluida en los estatutos y debidamente inscrita en el Registro de la Propiedad puede prohibir el uso de una vivienda como alojamiento tur\u00edstico.<\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\"><span class=\"s6\"><b>Cumplimiento de las normas de la comunidad y notificaci\u00f3n a los hu\u00e9spedes.<br \/>\n<\/b>Seg\u00fan lo establecido en el art\u00edculo 16.2 del Decreto 92\/2009, el precio del alquiler de alojamientos tur\u00edsticos, salvo que se indique o pacte expresamente lo contrario, incluye el uso de los elementos comunes y accesorios del propio alojamiento, incluidas piscinas, jardines, hamacas y terrazas o zonas de juegos infantiles comunitarias.<\/span><\/span>El Art\u00edculo 16.2 tambi\u00e9n enfatiza que \u00abel uso de estos elementos estar\u00e1 sujeto a las normas de uso de la comunidad de propietarios\u00bb. Por otro lado, el Art\u00edculo 9.3 recuerda a los hu\u00e9spedes que \u00ablos hu\u00e9spedes respetar\u00e1n las instalaciones, tanto del alojamiento tur\u00edstico como de los elementos comunes del edificio o urbanizaci\u00f3n\u00bb. En consecuencia, el propietario debe informar a los usuarios sobre las normas b\u00e1sicas que puedan afectar al uso de la propiedad y\/o los elementos comunes, preferiblemente proporcion\u00e1ndoles un folleto que resuma estas obligaciones y\/o restricciones. Estas normas comunitarias pueden tener su origen en los estatutos o incluso en reglamentos acordados por la comunidad de propietarios. Es responsabilidad del propietario familiarizarse con todas estas normas e informar a los hu\u00e9spedes sobre cualquier normativa que pueda afectar al uso del alojamiento o de las zonas\/elementos comunes, como el horario y la normativa de apertura de la piscina, las normas de eliminaci\u00f3n de residuos, la normativa sobre ruido, etc.<\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\"><span class=\"s6\"><b>Obligaciones del propietario con la comunidad<\/b><\/span><\/span><span class=\"s6\"><span class=\"s6\"><b><\/b>El propietario puede ser responsable ante la Comunidad tanto por la<br \/>\nlas infracciones que \u00e9l mismo comete directamente, as\u00ed como las infracciones que puedan cometer los hu\u00e9spedes (que pagan) de su casa.<\/span><\/span><b>Recomendaci\u00f3n de medios para los propietarios<\/b><br \/>\nCuando una propiedad tiene varios propietarios, pueden surgir disputas entre ellos. Los derechos leg\u00edtimos de todos los propietarios pueden conciliarse con la ayuda de diversos servicios: los Colegios de Administradores de Fincas de Valencia-Castell\u00f3n y Alicante ponen a disposici\u00f3n de la ciudadan\u00eda sus Servicios de Medios y ofrecen un sistema alternativo a los procedimientos judiciales para la resoluci\u00f3n colaborativa de disputas.<br \/>\n<a href=\"https:\/\/aaffvalencia.es\/cemei\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/aaffvalencia.es\/cemei\/<\/span><\/a><br \/>\n<a href=\"https:\/\/www.coafa.es\/mediacion-del-colegio\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/www.coafa.es\/mediacion-del-colegio\/<\/span><\/a><br \/>\n<a href=\"https:\/\/aaffvalencia.es\/cemei\/clausulas-contractuales-de-mediacion\/\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">https:\/\/aaffvalencia.es\/cemei\/clausulas-contractuales-de-mediacion\/<\/span><\/a><\/li>\n<\/ol>\n<h3 class=\"p11\"><b>2.9. Cumplimiento del RGPD<\/b><\/h3>\n<p class=\"p14\">Los datos personales tratados y recogidos durante la prestaci\u00f3n del servicio de alquiler vacacional deber\u00e1n ser:<\/p>\n<ol class=\"ol2\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">tratados de manera l\u00edcita, justa y transparente en relaci\u00f3n con el hu\u00e9sped;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos, y no ser\u00e1n utilizados posteriormente para ning\u00fan otro fin que aquel para el que fueron expl\u00edcitamente facilitados;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">\u00fanicamente relevantes y limitados a los datos personales necesarios para llevar a cabo la reserva u otras obligaciones legales y fiscales;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">almacenados de forma segura para salvaguardar y proteger la identidad de las partes interesadas y no se conservar\u00e1n durante m\u00e1s tiempo del necesario para los fines para los que se procesan los datos personales;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">tratados de tal manera que se garantice una seguridad adecuada de los datos personales, incluida la protecci\u00f3n contra el acceso no autorizado o ilegal (pirater\u00eda inform\u00e1tica) y contra la p\u00e9rdida, destrucci\u00f3n o da\u00f1o accidental, mediante la aplicaci\u00f3n de medidas t\u00e9cnicas u organizativas apropiadas.<\/span><\/li>\n<\/ol>\n<p class=\"p14\">El propietario o administrador de propiedad autorizado debe proporcionar toda la informaci\u00f3n que se detalla a continuaci\u00f3n:<\/p>\n<ol class=\"ol2\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">la identidad y los datos de contacto de la persona jur\u00eddica (y de su representante, si corresponde) responsable del tratamiento de los datos personales;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">los datos de contacto del Delegado de Protecci\u00f3n de Datos, en su caso;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">una indicaci\u00f3n clara de c\u00f3mo se utilizar\u00e1n los datos y la base legal para su utilizaci\u00f3n;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">los intereses leg\u00edtimos del responsable del tratamiento o del encargado del tratamiento o de un tercero que tambi\u00e9n tendr\u00e1 acceso a los datos personales y los utilizar\u00e1;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">la identidad y los datos de contacto de cualquier encargado del tratamiento de datos o de terceros que tengan acceso a los datos personales, en su caso;<\/span><\/li>\n<\/ol>\n<p class=\"p14\">Adem\u00e1s, el Propietario deber\u00e1 informar a los hu\u00e9spedes de la siguiente informaci\u00f3n necesaria para garantizar el almacenamiento y uso justo y transparente de sus datos personales:<\/p>\n<ol class=\"ol2\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">el per\u00edodo durante el cual se conservar\u00e1n los datos personales o, si esto no es posible, los criterios utilizados para determinar dicho per\u00edodo;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">la existencia del derecho a solicitar el acceso a sus datos personales, su recogida o supresi\u00f3n, o la limitaci\u00f3n de su tratamiento, o a oponerse al tratamiento, as\u00ed como el derecho a la portabilidad.<\/span><\/li>\n<\/ol>\n<p class=\"p14\">Por \u00faltimo, los propietarios y las empresas gestoras de fincas autorizadas deber\u00e1n garantizar el cumplimiento del RGPD \u2013 Reglamento General de Protecci\u00f3n de Datos del 26 de mayo de 2018.<\/p>\n<h3 class=\"p14\"><b>2.10. Obligaciones fiscales y laborales relativas a los empleados, tales como personal de limpieza y otros prestadores de servicios subcontratados.<\/b><\/h3>\n<p class=\"p14\">Por favor consulte el siguiente enlace: \u00a0<span class=\"s1\"><a href=\"https:\/\/aaffvalencia.es\/legislacion-inmobiliaria\/vivienda\/\" target=\"_blank\" rel=\"noopener\">https:\/\/aaffvalencia.es\/legislacion-inmobiliaria\/vivienda\/<b><\/b><\/a><\/span><\/p>\n<h2 class=\"p11\"><b>3.0 Derechos del propietario de la vivienda vacacional<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h2>\n<h3 class=\"p14\"><b>3.1. DERECHO A SOLICITAR UN DEP\u00d3SITO<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p class=\"p14\">El propietario se reserva el derecho, salvo acuerdo previo, de solicitar un dep\u00f3sito de hasta 250 \u20ac por da\u00f1os o p\u00e9rdida de las instalaciones y por un aumento del n\u00famero de hu\u00e9spedes. Este dep\u00f3sito se registrar\u00e1 al formalizar el contrato entre el hu\u00e9sped y el propietario o administrador autorizado. Una vez desocupada la propiedad, se le reembolsar\u00e1 al hu\u00e9sped, deduciendo cualquier descuento.<\/p>\n<h3 class=\"p11\"><b>3.2. DERECHOS EN CASO DE CANCELACI\u00d3N DE UNA RESERVA<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p class=\"p14\">El propietario o la empresa gestora reconocida de la vivienda tur\u00edstica deber\u00e1 poner a disposici\u00f3n de los clientes las viviendas en alquiler que cumplan las caracter\u00edsticas pactadas.<\/p>\n<p class=\"p14\">En caso de cancelaci\u00f3n por parte del hu\u00e9sped, el porcentaje a reembolsar deber\u00e1 especificarse previamente en el contrato. La compensaci\u00f3n para el propietario puede oscilar entre 10 y 100%.<\/p>\n<p class=\"p14\">En caso de cancelaci\u00f3n de la reserva por parte del propietario, el hu\u00e9sped tiene la opci\u00f3n de:<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<ol class=\"ol2\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">Aceptar una alternativa de alojamiento ofrecida con caracter\u00edsticas y categor\u00eda iguales o superiores.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Aceptar una compensaci\u00f3n monetaria por un monto igual al DOBLE del monto del pago inicial.<\/span><\/li>\n<\/ol>\n<h3 class=\"p11\"><b>3.3. DERECHOS EN CASO DE NO PRESENTACI\u00d3N.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p class=\"p14\">P\u00e9rdida de la reserva y del prepago. Si el hu\u00e9sped no llega en la fecha indicada y, por lo tanto, no ocupa la propiedad sin previo aviso de la nueva fecha de llegada, el propietario podr\u00e1 cancelar la reserva y el hu\u00e9sped no tendr\u00e1 derecho a reembolso del prepago realizado.<\/p>\n<h3 class=\"p11\"><b>3.4. DERECHOS DE LOS HU\u00c9SPEDES A DISFRUTAR DE LAS INSTALACIONES.<span class=\"Apple-converted-space\">\u00a0<\/span><\/b><\/h3>\n<p class=\"p14\">Los hu\u00e9spedes deber\u00e1n respetar las instalaciones del establecimiento, as\u00ed como los elementos comunes del edificio o urbanizaci\u00f3n.<\/p>\n<h3 class=\"p11\"><b>3.5. DERECHO A MEDIACI\u00d3N en caso de disputa entre el propietario y el hu\u00e9sped.<\/b><\/h3>\n<ol class=\"ol2\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">Si el n\u00famero de hu\u00e9spedes excede la capacidad m\u00e1xima del alojamiento o, en su caso, el n\u00famero de hu\u00e9spedes permitido seg\u00fan lo establecido en el contrato.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Subpr\u00e9stamo. Cesi\u00f3n del uso de inmuebles tur\u00edsticos a terceros.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Realizar cualquier actividad que atente contra las pr\u00e1cticas habituales de convivencia, higiene y orden p\u00fablico, o que altere la normal tranquilidad de los dem\u00e1s usuarios del inmueble.<\/span><\/li>\n<\/ol>\n<h2 class=\"p11\"><b>4.0 MULTAS Y SANCIONES<\/b><\/h2>\n<p class=\"p14\">Los propietarios de viviendas tur\u00edsticas deber\u00e1n velar por no infringir y prestar especial atenci\u00f3n a lo siguiente:<\/p>\n<p class=\"p11\"><b>Infracciones MENORES:<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">No exhibir de forma visible en la entrada del inmueble, tanto en el interior como en el exterior del mismo, la placa con el n\u00famero de matr\u00edcula y categor\u00eda; o exhibir un distintivo que no corresponda al inmueble.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Trato incorrecto a los hu\u00e9spedes.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Mala limpieza y mantenimiento de edificios, instalaciones, mobiliario e inventario.<span class=\"Apple-converted-space\">\u00a0<\/span><\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">No conservar copias de facturas u otros documentos.<\/span><\/li>\n<\/ul>\n<p class=\"p11\"><b>Violaciones GRAVES:<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">Publicidad falsa o enga\u00f1osa.<\/span><\/li>\n<\/ul>\n<p class=\"p14\">\u2022 Falta de servicio o servicio deficiente, o deterioro de las instalaciones.<\/p>\n<p class=\"p14\">\u2022 Falta de libros de reclamaciones a disposici\u00f3n de los hu\u00e9spedes, o negativa a hacerlo cuando se les solicita, sin motivo v\u00e1lido.<\/p>\n<p class=\"p14\">\u2022 Incumplimiento del contrato o de las condiciones pactadas, en cuanto a lugar, tiempo, precio u otros elementos que integran las condiciones del alojamiento tur\u00edstico contratado.<\/p>\n<p class=\"p14\">\u2022 Incumplimiento de los t\u00e9rminos y condiciones relativos a la reserva de la propiedad o cancelaci\u00f3n de la reserva.<\/p>\n<p class=\"p14\">\u2022 Pedir un precio m\u00e1s alto que el anunciado<\/p>\n<p class=\"p14\">\u2022 Negativa a emitir factura.<\/p>\n<p class=\"p14\">\u2022 Obstrucci\u00f3n del acceso o derechos del Inspector de Turismo.<\/p>\n<p class=\"p11\"><b>Violaciones MUY GRAVES<\/b><\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">El incumplimiento de los requisitos esenciales establecidos en la normativa vigente, as\u00ed como la falta de la documentaci\u00f3n exigida;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">El incumplimiento de las normas de prevenci\u00f3n y seguridad contra incendios; de las normas de seguridad; y de las normas de salud e higiene cuando ello suponga un riesgo grave para la salud y el bienestar de la poblaci\u00f3n.<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">Incumplimiento de las obligaciones de publicidad y comunicaci\u00f3n en la se\u00f1alizaci\u00f3n de establecimientos tur\u00edsticos.<\/span><\/li>\n<\/ul>\n<p class=\"p14\">Las sanciones descritas en la decisi\u00f3n son: \u2013<\/p>\n<ul class=\"ul1\">\n<li class=\"li12\"><b><\/b><span class=\"s6\">advertencia y multa de hasta 601 \u20ac por infracciones LEVES;<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">multa de hasta 6.010 \u20ac y suspensi\u00f3n o clausura por un periodo de hasta seis meses por infracciones graves, y<\/span><\/li>\n<li class=\"li12\"><b><\/b><span class=\"s6\">multa de hasta 90.151,82 \u20ac y clausura o suspensi\u00f3n de hasta tres a\u00f1os.<\/span><\/li>\n<\/ul>\n<p class=\"p11\"><b>Normativa tur\u00edstica aplicable al alquiler vacacional en la Comunidad Valenciana<\/b><\/p>\n<p class=\"p14\"><b>Leyes:<\/b><br \/>\n<a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/files\/pdf\/ley_de_turismo.pdf\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">Ley 3\/1998 de Turismo<\/span><\/a> de la Comunidad Valenciana, de 21 de mayo de 1998, en particular sus art\u00edculos 7, 7 bis, 8, 14, 15, 16, 18 y 18 bis.<\/p>\n<p class=\"p14\"><b>Pedidos:<\/b><\/p>\n<p class=\"p14\"><span class=\"s1\"><a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/files\/pdf\/tramitacion\/empresa_turistica\/Orden_2_2010x_de_29_de_marzox_distintivos_correspondientes_a_las_empresas_y_a_los_establecimeintos_turxsticos_de_la_Comunitat_Valenciana.pdf\" target=\"_blank\" rel=\"noopener\">Decisi\u00f3n 2\/2010<\/a><\/span> de 29 de marzo de 2010, para la colocaci\u00f3n de la se\u00f1alizaci\u00f3n correspondiente a los establecimientos y negocios tur\u00edsticos de la Comunidad Valenciana y en particular sus art\u00edculos 1, 2 y 3.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p14\"><b>Decretos:<\/b><\/p>\n<p class=\"p14\">Comunidad Aut\u00f3noma Valenciana <a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/files\/pdf\/tramitacion\/empresa_turistica\/decreto_77-1994.pdf\" target=\"_blank\" rel=\"noopener\"><span class=\"s1\">Decreto N\u00ba 77\/1994 <\/span><\/a>de 12 de abril de 1994, por la que se regula la puesta a disposici\u00f3n de los consumidores y usuarios de servicios de hojas de reclamaciones en la Comunidad Valenciana, y en particular sus art\u00edculos 1, 2, 3 y 4.<\/p>\n<p class=\"p14\"><span class=\"s1\"><a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/files\/pdf\/tramitacion\/empresa_turistica\/DECRETO_19.pdf\" target=\"_blank\" rel=\"noopener\">Decreto n\u00ba 19\/1997<\/a><\/span> de 11 de febrero de 1997, por el que se regula el r\u00e9gimen de precios y reservas aplicable en los alquileres tur\u00edsticos, y en particular sus art\u00edculos 1, 2, 3, 4, 5, 6, 8, 9, 10, 11, 12 y 13.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p class=\"p14\"><span class=\"s1\"><a href=\"https:\/\/www.turisme.gva.es\/opencms\/opencms\/turisme\/es\/files\/pdf\/tramitacion\/empresa_turistica\/Decreto_92_2009.pdf\" target=\"_blank\" rel=\"noopener\">Decreto N\u00ba 92\/2009<\/a><\/span> de 2 de julio de 2009, por el que se establece el r\u00e9gimen de las empresas de alquiler tur\u00edstico y de las sociedades gestoras de las mismas en la Comunidad Valenciana, en particular sus art\u00edculos 1, 2, 4, 5, 6, 8, 9, 10, 11, 12, 15, 16 y 20,<\/p>","protected":false},"excerpt":{"rendered":"<p>Dit is een Nederlandse vertaling van deOffici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen. Er kunnen geen rechten worden ontleend aan deze pagina en\/of de vertaling. Espanol: Consejo General de&#8230;<\/p>","protected":false},"author":1,"featured_media":1812,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[133],"class_list":["post-1803","post","type-post","status-publish","format-standard","has-post-thumbnail","category-geen-onderdeel-van-een-categorie","tag-turisme-comunitat-valenciana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen - Casa Benissa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen\" \/>\n<meta property=\"og:description\" content=\"Dit is een Nederlandse vertaling van deOffici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen. Er kunnen geen rechten worden ontleend aan deze pagina en\/of de vertaling. Espanol: Consejo General de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Benissa\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-10T19:16:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-08T09:00:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#\\\/schema\\\/person\\\/4c095ed42d73bb5e8c5f82f7f70c092c\"},\"headline\":\"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen\",\"datePublished\":\"2022-10-10T19:16:02+00:00\",\"dateModified\":\"2024-05-08T09:00:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/\"},\"wordCount\":3662,\"publisher\":{\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/wp-content\\\/uploads\\\/turisme-comunitat-valenciana.jpg\",\"keywords\":[\"turisme comunitat valenciana\"],\"articleSection\":[\"Geen onderdeel van een categorie\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/\",\"url\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/\",\"name\":\"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen - Casa Benissa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/wp-content\\\/uploads\\\/turisme-comunitat-valenciana.jpg\",\"datePublished\":\"2022-10-10T19:16:02+00:00\",\"dateModified\":\"2024-05-08T09:00:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/wp-content\\\/uploads\\\/turisme-comunitat-valenciana.jpg\",\"contentUrl\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/wp-content\\\/uploads\\\/turisme-comunitat-valenciana.jpg\",\"width\":1000,\"height\":651,\"caption\":\"turisme comunitat valenciana\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casabenissa.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#website\",\"url\":\"https:\\\/\\\/casabenissa.nl\\\/\",\"name\":\"Casa Benissa | Trainingslocatie in Spanje\",\"description\":\"Trainingslocatie in Costa Blanca - Spanje\",\"publisher\":{\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#organization\"},\"alternateName\":\"Huur een trainingslocatie in de Costa Blanca\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casabenissa.nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#organization\",\"name\":\"Casa Benissa\",\"url\":\"https:\\\/\\\/casabenissa.nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casabenissa.nl\\\/wp-content\\\/uploads\\\/Casa-benissa-logo.png\",\"contentUrl\":\"https:\\\/\\\/casabenissa.nl\\\/wp-content\\\/uploads\\\/Casa-benissa-logo.png\",\"width\":600,\"height\":300,\"caption\":\"Casa Benissa\"},\"image\":{\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/casabenissa.nl\\\/#\\\/schema\\\/person\\\/4c095ed42d73bb5e8c5f82f7f70c092c\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\"],\"url\":\"https:\\\/\\\/vh2023izdeb-0.hosting-space.nl\\\/es\\\/author\\\/patrick\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gu\u00eda oficial de la Comunidad Valenciana para propietarios de viviendas vacacionales - Casa Benissa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/","og_locale":"es_ES","og_type":"article","og_title":"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen","og_description":"Dit is een Nederlandse vertaling van deOffici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen. Er kunnen geen rechten worden ontleend aan deze pagina en\/of de vertaling. Espanol: Consejo General de...","og_url":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/","og_site_name":"Casa Benissa","article_published_time":"2022-10-10T19:16:02+00:00","article_modified_time":"2024-05-08T09:00:28+00:00","og_image":[{"width":1000,"height":651,"url":"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"19 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#article","isPartOf":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/"},"author":{"name":"admin","@id":"https:\/\/casabenissa.nl\/#\/schema\/person\/4c095ed42d73bb5e8c5f82f7f70c092c"},"headline":"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen","datePublished":"2022-10-10T19:16:02+00:00","dateModified":"2024-05-08T09:00:28+00:00","mainEntityOfPage":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/"},"wordCount":3662,"publisher":{"@id":"https:\/\/casabenissa.nl\/#organization"},"image":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg","keywords":["turisme comunitat valenciana"],"articleSection":["Geen onderdeel van een categorie"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/","url":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/","name":"Gu\u00eda oficial de la Comunidad Valenciana para propietarios de viviendas vacacionales - Casa Benissa","isPartOf":{"@id":"https:\/\/casabenissa.nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#primaryimage"},"image":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#primaryimage"},"thumbnailUrl":"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg","datePublished":"2022-10-10T19:16:02+00:00","dateModified":"2024-05-08T09:00:28+00:00","breadcrumb":{"@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#primaryimage","url":"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg","contentUrl":"https:\/\/vh2023izdeb-0.hosting-space.nl\/wp-content\/uploads\/turisme-comunitat-valenciana.jpg","width":1000,"height":651,"caption":"turisme comunitat valenciana"},{"@type":"BreadcrumbList","@id":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/guia-oficial-de-la-comunidad-de-valencia-para-propietarios-de-viviendas-vacacionales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casabenissa.nl\/"},{"@type":"ListItem","position":2,"name":"Offici\u00eble gemeenschapsgids van Valencia voor eigenaars van vakantiewoningen"}]},{"@type":"WebSite","@id":"https:\/\/casabenissa.nl\/#website","url":"https:\/\/casabenissa.nl\/","name":"Casa Benissa | Centro de formaci\u00f3n en Espa\u00f1a","description":"Lugar de entrenamiento en Costa Blanca - Espa\u00f1a","publisher":{"@id":"https:\/\/casabenissa.nl\/#organization"},"alternateName":"Huur een trainingslocatie in de Costa Blanca","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casabenissa.nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/casabenissa.nl\/#organization","name":"Casa Benissa","url":"https:\/\/casabenissa.nl\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/casabenissa.nl\/#\/schema\/logo\/image\/","url":"https:\/\/casabenissa.nl\/wp-content\/uploads\/Casa-benissa-logo.png","contentUrl":"https:\/\/casabenissa.nl\/wp-content\/uploads\/Casa-benissa-logo.png","width":600,"height":300,"caption":"Casa Benissa"},"image":{"@id":"https:\/\/casabenissa.nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/casabenissa.nl\/#\/schema\/person\/4c095ed42d73bb5e8c5f82f7f70c092c","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d1216862b2d99de334b23d83da2f9df1b468849536459fd555f4c543e2030207?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/vh2023izdeb-0.hosting-space.nl"],"url":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/author\/patrick\/"}]}},"_links":{"self":[{"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/posts\/1803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":0,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/posts\/1803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/media\/1812"}],"wp:attachment":[{"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/media?parent=1803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/categories?post=1803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vh2023izdeb-0.hosting-space.nl\/es\/wp-json\/wp\/v2\/tags?post=1803"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}